{"id":61481,"date":"2025-11-13T11:05:58","date_gmt":"2025-11-13T11:05:58","guid":{"rendered":"https:\/\/psoecanarias.com\/web\/?post_type=persona_pods&#038;p=61481"},"modified":"2026-01-12T09:53:15","modified_gmt":"2026-01-12T09:53:15","slug":"anselmo-pestana-padron","status":"publish","type":"persona_pods","link":"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/","title":{"rendered":"Anselmo Pestana Padr\u00f3n"},"content":{"rendered":"<div>Nacido en Gu\u00eda de Isora, Canarias.<\/div>\n<div><\/div>\n<div><strong>M\u00e9ritos acad\u00e9micos\u00a0<\/strong><br \/>\nLicenciado en Derecho por la Universidad de La Laguna.<\/div>\n<div><\/div>\n<div><strong>Trayectoria profesional<\/strong><\/div>\n<div>En la actualidad es Delegado del Gobierno en Canarias desde febrero de 2020.<\/div>\n<div><\/div>\n<div>Ha ocupado los cargos de:<\/div>\n<ul>\n<li>\n<div role=\"presentation\">Concejal en el Ayuntamiento de Santa Cruz de La Palma entre los a\u00f1os 1999 y 2011, ocupando la Alcald\u00eda de\u00a0esa Corporaci\u00f3n Municipal durante los a\u00f1os 2006 y 2007. Tambi\u00e9n fue portavoz del Grupo Municipal Socialista desde 1999 hasta 2010, y primer teniente de alcalde y portavoz entre 2005 y 2006.<\/div>\n<\/li>\n<li>\n<div role=\"presentation\">\u00a0Diputado auton\u00f3mico en el Parlamento de Canarias, donde ejerci\u00f3 como portavoz de Agricultura, Ganader\u00eda, Pesca y Alimentaci\u00f3n., entre los a\u00f1os 2003 y 2008.<\/div>\n<\/li>\n<li>\n<div role=\"presentation\">Senador por la isla de La Palma en el periodo 2007-2011.<\/div>\n<\/li>\n<li>\n<div role=\"presentation\">Consejero del Cabildo de La Palma desde 2011, siendo portavoz del Grupo Socialista, vicepresidente primero de 2011 a 2013 y presidente de 2013 a 2015. Tambi\u00e9n ha sido presidente del Cabildo Insular de La Palma durante el mandato 2015-2019 y vicepresidente del mismo hasta su nombramiento como delegado del Gobierno en Canarias a principios de 2020<\/div>\n<\/li>\n<\/ul>\n<div>Por otro lado, es letrado del Cabildo Insular de La Palma desde 1991, donde ostenta la plaza de jefe del Servicio de R\u00e9gimen Jur\u00eddico, actualmente en situaci\u00f3n de servicios especiales.<\/div>\n<div><\/div>\n<div><strong>Trayectoria org\u00e1nica<\/strong><\/div>\n<div><\/div>\n<div>Milita en el PSOE desde 1993. En la actualidad es Secretario de \u00c1rea de Coordinaci\u00f3n Territorial y Relaciones Institucionales y miembro del Comit\u00e9 Federal.<\/div>\n<div><\/div>\n<div>Ha desempe\u00f1ado las responsabilidades de:<\/div>\n<ul>\n<li>\n<div role=\"presentation\">Secretario General del PSOE en La Palma (2013-2025)<\/div>\n<\/li>\n<li>\n<div role=\"presentation\">Secretario General del PSOE en Santa Cruz de La Palma (1996-2012)<\/div>\n<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a href=\"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2026\/01\/PESTANA-PADRON.odt\"><em>Descargar informaci\u00f3n en formato editable<\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nacido en Gu\u00eda de Isora, Canarias. M\u00e9ritos acad\u00e9micos\u00a0 Licenciado en Derecho por la Universidad de La Laguna. Trayectoria profesional En la actualidad es Delegado del Gobierno en Canarias desde febrero de 2020. Ha ocupado los cargos de: Concejal en el Ayuntamiento de Santa Cruz de La Palma entre los a\u00f1os 1999 y 2011, ocupando la [&hellip;]<\/p>\n","protected":false},"featured_media":8406,"template":"","seccion_pods":[1179],"class_list":["post-61481","persona_pods","type-persona_pods","status-publish","has-post-thumbnail","hentry","seccion_pods-comision-ejecutiva-regional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anselmo Pestana Padr\u00f3n | PSOE Canarias<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anselmo Pestana Padr\u00f3n | PSOE Canarias\" \/>\n<meta property=\"og:description\" content=\"Nacido en Gu\u00eda de Isora, Canarias. M\u00e9ritos acad\u00e9micos\u00a0 Licenciado en Derecho por la Universidad de La Laguna. Trayectoria profesional En la actualidad es Delegado del Gobierno en Canarias desde febrero de 2020. Ha ocupado los cargos de: Concejal en el Ayuntamiento de Santa Cruz de La Palma entre los a\u00f1os 1999 y 2011, ocupando la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/\" \/>\n<meta property=\"og:site_name\" content=\"PSOE Canarias\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T09:53:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/\",\"url\":\"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/\",\"name\":\"Anselmo Pestana Padr\u00f3n | PSOE Canarias\",\"isPartOf\":{\"@id\":\"https:\/\/psoecanarias.com\/web\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2020\/03\/thumb_noimages.jpg\",\"datePublished\":\"2025-11-13T11:05:58+00:00\",\"dateModified\":\"2026-01-12T09:53:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/#primaryimage\",\"url\":\"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2020\/03\/thumb_noimages.jpg\",\"contentUrl\":\"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2020\/03\/thumb_noimages.jpg\",\"width\":303,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/psoecanarias.com\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anselmo Pestana Padr\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/psoecanarias.com\/web\/#website\",\"url\":\"https:\/\/psoecanarias.com\/web\/\",\"name\":\"PSOE Canarias\",\"description\":\"Partido Socialista Obrero Espa\u00f1ol Canarias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/psoecanarias.com\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anselmo Pestana Padr\u00f3n | PSOE Canarias","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Anselmo Pestana Padr\u00f3n | PSOE Canarias","og_description":"Nacido en Gu\u00eda de Isora, Canarias. M\u00e9ritos acad\u00e9micos\u00a0 Licenciado en Derecho por la Universidad de La Laguna. Trayectoria profesional En la actualidad es Delegado del Gobierno en Canarias desde febrero de 2020. Ha ocupado los cargos de: Concejal en el Ayuntamiento de Santa Cruz de La Palma entre los a\u00f1os 1999 y 2011, ocupando la [&hellip;]","og_url":"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/","og_site_name":"PSOE Canarias","article_modified_time":"2026-01-12T09:53:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/","url":"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/","name":"Anselmo Pestana Padr\u00f3n | PSOE Canarias","isPartOf":{"@id":"https:\/\/psoecanarias.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/#primaryimage"},"image":{"@id":"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/#primaryimage"},"thumbnailUrl":"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2020\/03\/thumb_noimages.jpg","datePublished":"2025-11-13T11:05:58+00:00","dateModified":"2026-01-12T09:53:15+00:00","breadcrumb":{"@id":"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/#primaryimage","url":"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2020\/03\/thumb_noimages.jpg","contentUrl":"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2020\/03\/thumb_noimages.jpg","width":303,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/psoecanarias.com\/web\/persona-pods\/anselmo-pestana-padron\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/psoecanarias.com\/web\/"},{"@type":"ListItem","position":2,"name":"Anselmo Pestana Padr\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/psoecanarias.com\/web\/#website","url":"https:\/\/psoecanarias.com\/web\/","name":"PSOE Canarias","description":"Partido Socialista Obrero Espa\u00f1ol Canarias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/psoecanarias.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/persona_pods\/61481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/persona_pods"}],"about":[{"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/types\/persona_pods"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/media\/8406"}],"wp:attachment":[{"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/media?parent=61481"}],"wp:term":[{"taxonomy":"seccion_pods","embeddable":true,"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/seccion_pods?post=61481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}