{"id":20231,"date":"2021-09-26T13:29:37","date_gmt":"2021-09-26T12:29:37","guid":{"rendered":"http:\/\/psoecanarias.com\/web\/?p=20231"},"modified":"2021-09-26T13:29:37","modified_gmt":"2021-09-26T12:29:37","slug":"el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio","status":"publish","type":"post","link":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/","title":{"rendered":"El PSOE impulsa la creaci\u00f3n de un tel\u00e9fono gratuito de atenci\u00f3n a v\u00edctimas de delitos de odio"},"content":{"rendered":"<p class=\"western\" lang=\"es-ES-u-co-trad\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\"><b>Canarias, 26 de septiembre de 2021.-<\/b><\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\"> El Grupo Parlamentario Socialista propondr\u00e1 en la sesi\u00f3n plenaria de la pr\u00f3xima semana (d\u00edas 28 y 29) la puesta en marcha de un tel\u00e9fono gratuito dirigido a dar atenci\u00f3n a posibles v\u00edctimas de delitos de odio. La iniciativa, en forma de Proyecto No de Ley (PNL), ser\u00e1 defendida por el diputado Omar L\u00f3pez Gonz\u00e1lez y plantea habilitar un servicio confidencial que ofrezca cobertura a quienes se puedan ver envueltos en un incidente relacionado con su orientaci\u00f3n sexual o identidad de g\u00e9nero y necesiten asesoramiento jur\u00eddico o apoyo psicol\u00f3gico. <\/span><\/span><\/span><\/p>\n<p class=\"western\" lang=\"es-ES-u-co-trad\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\">&#8220;Muchas de la v\u00edctimas de delitos de odio a causa de la <\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\"><i>LGTBIfobia<\/i><\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\"> demandan, seg\u00fan los estudios realizados tanto p\u00fablicos como privados, v\u00edas de apoyo y asesoramiento de forma telem\u00e1tica y presencial, que les permita mantener el anonimato, si as\u00ed lo considerasen oportuno, debido al momento vital que est\u00e9n atravesando&#8221;, ha asegurado Omar L\u00f3pez.<\/span><\/span><\/span><\/p>\n<p class=\"western\" lang=\"es-ES-u-co-trad\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\">El fin, ha a\u00f1adido, &#8220;es seguir dando pasos a favor de una sociedad diversa y segura\u201d, al mismo tiempo que disponer de una herramienta que pueda ser \u00fatil para \u201caquellas personas que sufren a diario el acoso y la marginaci\u00f3n de su c\u00edrculo m\u00e1s cercano sin posibilidad de salir corriendo ni recibir ayuda\u201d.<\/span><\/span><\/span><\/p>\n<p class=\"western\" lang=\"es-ES-u-co-trad\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\">Pese a contar Espa\u00f1a con una de las sociedades m\u00e1s comprometidas con la diversidad, es un hecho que \u201csigue existiendo una parte de la sociedad\u00a0<\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\">que discrimina al diferente, acosando e incluso agrediendo a personas por una \u00fanica raz\u00f3n: su orientaci\u00f3n sexual o su identidad de g\u00e9nero\u201d. <\/span><\/span><\/span><\/p>\n<p class=\"western\" lang=\"es-ES-u-co-trad\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\">Ah\u00ed est\u00e1n los datos del Ministerio del Interior que confirman \u201cun aumento de los delitos de odio desde el a\u00f1o 2014\u201d, seguramente influenciados por el blanqueamiento de determinados discursos pol\u00edticos y la negaci\u00f3n de la <\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\"><i>LGTBIfobia<\/i><\/span><\/span><\/span><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\">, ha lamentado el diputado del Grupo Parlamentario de los socialistas canarios.<\/span><\/span><\/span><\/p>\n<p class=\"western\" lang=\"es-ES-u-co-trad\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\">Con la puesta en marcha de este servicio telef\u00f3nico en Canarias, se trata de \u201cdar voz\u201d a quienes puedan estar sufriendo este tipo de acoso en silencio, ya sea en su domicilio o en el \u00e1mbito laboral, y brindar una oportunidad de ayuda disponible hasta \u201cen el \u00faltimo rinc\u00f3n donde haya tan s\u00f3lo una persona que est\u00e9 viviendo esta angustia\u201d. <\/span><\/span><\/span><\/p>\n<p class=\"western\" lang=\"es-ES-u-co-trad\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\">Omar L\u00f3pez conf\u00eda en que la propuesta socialista concite el apoyo de todas las fuerzas pol\u00edticas con representaci\u00f3n parlamentario, repitiendo as\u00ed la unidad que permiti\u00f3 hace pocos meses sacar adelante por unanimidad la ley trans canaria. \u201cTodos aportamos color a estas islas, y fuimos ejemplo de unidad y supimos dejar a un lado las discrepancias que normalmente nos separan\u201d.<\/span><\/span><\/span><\/p>\n<p class=\"western\" lang=\"es-ES-u-co-trad\" align=\"justify\"><span style=\"font-family: Arial, serif;\"><span style=\"font-size: large;\"><span lang=\"es-ES-u-co-trad\">La Proposici\u00f3n No de Ley que debatir\u00e1 el pleno del Parlamento de Canarias insta al Gobierno de Canarias a la \u201chabilitaci\u00f3n de un tel\u00e9fono gratuito para atender los delitos de odio por homofobia, orientaci\u00f3n sexual e identidad de g\u00e9nero, que sirva para asesorar jur\u00eddicamente y de apoyo psicol\u00f3gico\u201d, as\u00ed como a \u201cestudiar, si fuera posible, y su posterior puesta en marcha, de un servicio presencial que complemente esta prestaci\u00f3n\u201d.<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El diputado Omar L\u00f3pez defender\u00e1 el Proyecto No de Ley en la pr\u00f3xima sesi\u00f3n plenaria <\/p>\n","protected":false},"author":1,"featured_media":20232,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1185,1184],"tags":[],"class_list":["post-20231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grupo-parlamentario","category-noticias"],"featured_image_src":"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2021\/09\/omar-lopez2.jpg","author_info":{"display_name":"PSOE Canarias","author_link":"https:\/\/psoecanarias.com\/web\/author\/admin\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El PSOE impulsa la creaci\u00f3n de un tel\u00e9fono gratuito de atenci\u00f3n a v\u00edctimas de delitos de odio | PSOE Canarias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PSOE impulsa la creaci\u00f3n de un tel\u00e9fono gratuito de atenci\u00f3n a v\u00edctimas de delitos de odio | PSOE Canarias\" \/>\n<meta property=\"og:description\" content=\"El diputado Omar L\u00f3pez defender\u00e1 el Proyecto No de Ley en la pr\u00f3xima sesi\u00f3n plenaria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/\" \/>\n<meta property=\"og:site_name\" content=\"PSOE Canarias\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-26T12:29:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2021\/09\/omar-lopez2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"PSOE Canarias\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/\"},\"author\":{\"name\":\"PSOE Canarias\",\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/#\\\/schema\\\/person\\\/1ae43f9659d2fc599ca69c11e1dbf26f\"},\"headline\":\"El PSOE impulsa la creaci\u00f3n de un tel\u00e9fono gratuito de atenci\u00f3n a v\u00edctimas de delitos de odio\",\"datePublished\":\"2021-09-26T12:29:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/\"},\"wordCount\":547,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/omar-lopez2.jpg\",\"articleSection\":[\"Grupo Parlamentario\",\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/\",\"url\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/\",\"name\":\"El PSOE impulsa la creaci\u00f3n de un tel\u00e9fono gratuito de atenci\u00f3n a v\u00edctimas de delitos de odio | PSOE Canarias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/omar-lopez2.jpg\",\"datePublished\":\"2021-09-26T12:29:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/#\\\/schema\\\/person\\\/1ae43f9659d2fc599ca69c11e1dbf26f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/omar-lopez2.jpg\",\"contentUrl\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/omar-lopez2.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"Omar L\u00f3pez, diputado socialista\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PSOE impulsa la creaci\u00f3n de un tel\u00e9fono gratuito de atenci\u00f3n a v\u00edctimas de delitos de odio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/\",\"name\":\"PSOE Canarias\",\"description\":\"Partido Socialista Obrero Espa\u00f1ol Canarias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/#\\\/schema\\\/person\\\/1ae43f9659d2fc599ca69c11e1dbf26f\",\"name\":\"PSOE Canarias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4364d37f6f6f9cdb7af199b46151565f37d8a8c3c0e04c1d78c04e857a15e3a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4364d37f6f6f9cdb7af199b46151565f37d8a8c3c0e04c1d78c04e857a15e3a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4364d37f6f6f9cdb7af199b46151565f37d8a8c3c0e04c1d78c04e857a15e3a8?s=96&d=mm&r=g\",\"caption\":\"PSOE Canarias\"},\"url\":\"https:\\\/\\\/psoecanarias.com\\\/web\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PSOE impulsa la creaci\u00f3n de un tel\u00e9fono gratuito de atenci\u00f3n a v\u00edctimas de delitos de odio | PSOE Canarias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/","og_locale":"es_ES","og_type":"article","og_title":"El PSOE impulsa la creaci\u00f3n de un tel\u00e9fono gratuito de atenci\u00f3n a v\u00edctimas de delitos de odio | PSOE Canarias","og_description":"El diputado Omar L\u00f3pez defender\u00e1 el Proyecto No de Ley en la pr\u00f3xima sesi\u00f3n plenaria","og_url":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/","og_site_name":"PSOE Canarias","article_published_time":"2021-09-26T12:29:37+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2021\/09\/omar-lopez2.jpg","type":"image\/jpeg"}],"author":"PSOE Canarias","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/#article","isPartOf":{"@id":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/"},"author":{"name":"PSOE Canarias","@id":"https:\/\/psoecanarias.com\/web\/#\/schema\/person\/1ae43f9659d2fc599ca69c11e1dbf26f"},"headline":"El PSOE impulsa la creaci\u00f3n de un tel\u00e9fono gratuito de atenci\u00f3n a v\u00edctimas de delitos de odio","datePublished":"2021-09-26T12:29:37+00:00","mainEntityOfPage":{"@id":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/"},"wordCount":547,"commentCount":0,"image":{"@id":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/#primaryimage"},"thumbnailUrl":"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2021\/09\/omar-lopez2.jpg","articleSection":["Grupo Parlamentario","Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/","url":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/","name":"El PSOE impulsa la creaci\u00f3n de un tel\u00e9fono gratuito de atenci\u00f3n a v\u00edctimas de delitos de odio | PSOE Canarias","isPartOf":{"@id":"https:\/\/psoecanarias.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/#primaryimage"},"image":{"@id":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/#primaryimage"},"thumbnailUrl":"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2021\/09\/omar-lopez2.jpg","datePublished":"2021-09-26T12:29:37+00:00","author":{"@id":"https:\/\/psoecanarias.com\/web\/#\/schema\/person\/1ae43f9659d2fc599ca69c11e1dbf26f"},"breadcrumb":{"@id":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/#primaryimage","url":"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2021\/09\/omar-lopez2.jpg","contentUrl":"https:\/\/psoecanarias.com\/web\/wp-content\/uploads\/2021\/09\/omar-lopez2.jpg","width":2048,"height":1365,"caption":"Omar L\u00f3pez, diputado socialista"},{"@type":"BreadcrumbList","@id":"https:\/\/psoecanarias.com\/web\/el-psoe-impulsa-la-creacion-de-un-telefono-gratuito-de-atencion-a-victimas-de-delitos-de-odio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/psoecanarias.com\/web\/"},{"@type":"ListItem","position":2,"name":"El PSOE impulsa la creaci\u00f3n de un tel\u00e9fono gratuito de atenci\u00f3n a v\u00edctimas de delitos de odio"}]},{"@type":"WebSite","@id":"https:\/\/psoecanarias.com\/web\/#website","url":"https:\/\/psoecanarias.com\/web\/","name":"PSOE Canarias","description":"Partido Socialista Obrero Espa\u00f1ol Canarias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/psoecanarias.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/psoecanarias.com\/web\/#\/schema\/person\/1ae43f9659d2fc599ca69c11e1dbf26f","name":"PSOE Canarias","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4364d37f6f6f9cdb7af199b46151565f37d8a8c3c0e04c1d78c04e857a15e3a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4364d37f6f6f9cdb7af199b46151565f37d8a8c3c0e04c1d78c04e857a15e3a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4364d37f6f6f9cdb7af199b46151565f37d8a8c3c0e04c1d78c04e857a15e3a8?s=96&d=mm&r=g","caption":"PSOE Canarias"},"url":"https:\/\/psoecanarias.com\/web\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/posts\/20231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/comments?post=20231"}],"version-history":[{"count":1,"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/posts\/20231\/revisions"}],"predecessor-version":[{"id":20233,"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/posts\/20231\/revisions\/20233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/media\/20232"}],"wp:attachment":[{"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/media?parent=20231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/categories?post=20231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/psoecanarias.com\/web\/wp-json\/wp\/v2\/tags?post=20231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}